{"id":970,"date":"2018-11-19T17:06:04","date_gmt":"2018-11-19T16:06:04","guid":{"rendered":"http:\/\/www.dietmarhalbauer.com\/wordpress\/?p=970"},"modified":"2024-09-27T09:11:15","modified_gmt":"2024-09-27T08:11:15","slug":"the-k-accident","status":"publish","type":"post","link":"https:\/\/www.dietmarhalbauer.com\/wordpress\/2018\/11\/the-k-accident\/","title":{"rendered":"The K Accident"},"content":{"rendered":"<p>Metal Burn, 2016<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04fe0808f3a&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04fe0808f3a\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"971\" src=\"http:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg\" alt=\"\" class=\"wp-image-971\" srcset=\"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg 800w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-170x170.jpg 170w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-300x300.jpg 300w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-768x768.jpg 768w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-640x640.jpg 640w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-50x50.jpg 50w, https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-600x600.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Metal Burn, 2016<\/p>\n","protected":false},"author":2,"featured_media":971,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[263],"tags":[43,42,101,69,88,102,100,45,46],"class_list":["post-970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abstract","tag-abstract","tag-blue","tag-burn","tag-contemporary","tag-dietmar-halbauer","tag-found","tag-metal","tag-splash","tag-structure"],"featured_media_urls":{"thumbnail":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-170x170.jpg",170,170,true],"medium":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-768x768.jpg",768,768,true],"large":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"1536x1536":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"2048x2048":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"ect-jetpack-portfolio-featured":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-640x640.jpg",640,640,true],"ect-featured-content":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-640x640.jpg",640,640,true],"ect-service":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-640x640.jpg",640,640,true],"inspiro-featured-image":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"inspiro-loop":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-800x320.jpg",800,320,true],"inspiro-loop@2x":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-800x640.jpg",800,640,true],"jetpack-portfolio-admin-thumb":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-50x50.jpg",50,50,true],"featured-content-admin-thumb":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-50x50.jpg",50,50,true],"service-admin-thumb":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-50x50.jpg",50,50,true],"portfolio_item-thumbnail":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-600x400.jpg",600,400,true],"portfolio_item-thumbnail@2x":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"portfolio_item-masonry":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-600x600.jpg",600,600,true],"portfolio_item-masonry@2x":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"portfolio_item-thumbnail_cinema":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-800x335.jpg",800,335,true],"portfolio_item-thumbnail_portrait":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-600x800.jpg",600,800,true],"portfolio_item-thumbnail_portrait@2x":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident.jpg",800,800,false],"portfolio_item-thumbnail_square":["https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-content\/uploads\/2017\/05\/the-k-accident-800x800.jpg",800,800,true]},"_links":{"self":[{"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/posts\/970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":2,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"predecessor-version":[{"id":2770,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/posts\/970\/revisions\/2770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/media\/971"}],"wp:attachment":[{"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dietmarhalbauer.com\/wordpress\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}